{"id":11827,"date":"2018-01-08T10:18:49","date_gmt":"2018-01-08T15:18:49","guid":{"rendered":"http:\/\/bbn1.bbnradio.org\/german\/?page_id=11827"},"modified":"2019-02-20T12:56:47","modified_gmt":"2019-02-20T17:56:47","slug":"zeitlose-botschaften-donnerstag","status":"publish","type":"page","link":"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/","title":{"rendered":"Zeitlose Botschaften &#8211; Donnerstag"},"content":{"rendered":"<div id='layer_slider_1'  class='avia-layerslider main_color avia-shadow  avia-builder-el-0  el_before_av_three_fifth  avia-builder-el-first  container_wrap sidebar_right'  style='height: 201px;'  ><\/div><div id='after_layer_slider_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-11827'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-56hi7kj-514cc09244c0fc5ccc473cce10d50e9a av_three_fifth  avia-builder-el-1  el_after_av_layerslider  el_before_av_two_fifth  avia-builder-el-first  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-d616361df0bf645f19fce89ce4e3680f\">\n#top .av-special-heading.av-av_heading-d616361df0bf645f19fce89ce4e3680f{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-av_heading-d616361df0bf645f19fce89ce4e3680f .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-d616361df0bf645f19fce89ce4e3680f .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-d616361df0bf645f19fce89ce4e3680f av-special-heading-h3  avia-builder-el-2  el_before_av_image  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Zeitlose Botschaften &#8211; Donnerstag<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4frx0fn-3d67c32fe89092196f3d4d94bf13cdd4\">\n.avia-image-container.av-4frx0fn-3d67c32fe89092196f3d4d94bf13cdd4 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-4frx0fn-3d67c32fe89092196f3d4d94bf13cdd4 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-4frx0fn-3d67c32fe89092196f3d4d94bf13cdd4 av-styling- avia-align-left  avia-builder-el-3  el_after_av_heading  el_before_av_textblock '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-14014 avia-img-lazy-loading-not-14014 avia_image ' src=\"https:\/\/bbn1.bbnradio.org\/german\/wp-content\/uploads\/sites\/9\/2019\/02\/Zeitlose-Botschaften-Missionswerk-Werner-Heukelbach.jpg\" alt='Zeitlose Botschaften - Missionswerk Werner Heukelbach' title='Zeitlose Botschaften - Missionswerk Werner Heukelbach'  height=\"628\" width=\"1200\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-43c0m1f-650d3adcdc9b1c4136d742d29ebe7159 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Missionswerk Werner Heukelbach<\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-3njjxn7-7e25e8a8a3639489faa7732dbc7f20a0 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><audio class=\"wp-audio-shortcode\" id=\"audio-11827-1\" autoplay preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/bbnradio.b-cdn.net\/german\/cG3ZB.m4a?_=1\" \/><a href=\"https:\/\/bbnradio.b-cdn.net\/german\/cG3ZB.m4a\">https:\/\/bbnradio.b-cdn.net\/german\/cG3ZB.m4a<\/a><\/audio>\n<\/div><\/section><br \/>\n<div  class='avia-button-wrap avia-button-center  avia-builder-el-6  el_after_av_textblock  avia-builder-el-last '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2y64pcj-568479857b7bb8b26da07c3c1ea592e9\">\n#top #wrap_all .avia-button.av-2y64pcj-568479857b7bb8b26da07c3c1ea592e9{\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n#top #wrap_all .avia-button.av-2y64pcj-568479857b7bb8b26da07c3c1ea592e9:hover{\nbackground-color:orange;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n#top #wrap_all .avia-button.av-2y64pcj-568479857b7bb8b26da07c3c1ea592e9 .avia-svg-icon svg:first-child{\nfill:#ffffff;\nstroke:#ffffff;\n}\n#top #wrap_all .avia-button.av-2y64pcj-568479857b7bb8b26da07c3c1ea592e9:hover .avia-svg-icon svg:first-child{\nfill:#ffffff;\nstroke:#ffffff;\n}\n<\/style>\n<a href='https:\/\/bbn1.bbnradio.org\/german\/spenden\/' class='avia-color-theme-color avia-button avia-button-fullwidth av-2y64pcj-568479857b7bb8b26da07c3c1ea592e9 avia-icon_select-no avia-color-theme-color'  target=\"_blank\"  rel=\"noopener noreferrer\"  aria-label=\"Spenden Sie jetzt!\"><span class='avia_iconbox_title' >Spenden Sie jetzt!<\/span><div class='av-button-description av-button-description-below'><p>BBN wird ausschlie\u00dflich von den Spenden der Zuh\u00f6rer finanziert.<\/p>\n<\/div><\/a><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2hseunn-cd13d5c6f547fc0b3461ef4e8ca6ceee\">\n.flex_column.av-2hseunn-cd13d5c6f547fc0b3461ef4e8ca6ceee{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-2hseunn-cd13d5c6f547fc0b3461ef4e8ca6ceee av_two_fifth  avia-builder-el-7  el_after_av_three_fifth  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1ywfonn-613588dd99b54e1cb7512919da762e38\">\n#top .avia-icon-list-container.av-1ywfonn-613588dd99b54e1cb7512919da762e38 .iconlist_icon{\ncolor:#003800;\nbackground-color:#ffffff;\nborder:1px solid #003800;\n}\n#top .avia-icon-list-container.av-1ywfonn-613588dd99b54e1cb7512919da762e38 .iconlist_icon svg:first-child{\nstroke:#003800;\nfill:#003800;\n}\n<\/style>\n<div  class='avia-icon-list-container av-1ywfonn-613588dd99b54e1cb7512919da762e38  avia-builder-el-8  avia-builder-el-no-sibling '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-big av-1ywfonn-613588dd99b54e1cb7512919da762e38 avia-iconlist-animate'>\n<li><a href='https:\/\/bbn1.bbnradio.org\/german\/start\/' title='Zum ersten Mal hier?'  target=\"_blank\"  rel=\"noopener noreferrer\" class='iconlist_icon av-1ii8ooj-07f53179de3cfdd5c43d1050d0fafe76 avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue871' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/a><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: &lt;a href=&#039;https:\/\/bbn1.bbnradio.org\/german\/start\/&#039; title=&#039;Zum ersten Mal hier?&#039; target=&quot;_blank&quot;  rel=&quot;noopener noreferrer&quot;&gt;Zum ersten Mal hier?&lt;\/a&gt;\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" ><a href='https:\/\/bbn1.bbnradio.org\/german\/start\/' title='Zum ersten Mal hier?' target=\"_blank\"  rel=\"noopener noreferrer\">Zum ersten Mal hier?<\/a><\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><p>Startseite<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='https:\/\/bbn1.bbnradio.org\/german\/christliches-online-radio-ohne-werbung\/apps\/' title='App installieren'  class='iconlist_icon av-1brmjo3-7cc6a9efa14045d7099e1b41787faf54 avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue8ac' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: &lt;a href=&#039;https:\/\/bbn1.bbnradio.org\/german\/christliches-online-radio-ohne-werbung\/apps\/&#039; title=&#039;App installieren&#039;&gt;App installieren&lt;\/a&gt;\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" ><a href='https:\/\/bbn1.bbnradio.org\/german\/christliches-online-radio-ohne-werbung\/apps\/' title='App installieren'>App installieren<\/a><\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-missionswerk-werner-heukelbach\/' title='Programm-Info'  target=\"_blank\"  rel=\"noopener noreferrer\" class='iconlist_icon av-qskmab-683994d2fae534d4429b1ceb93ea4acf avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue81e' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: &lt;a href=&#039;https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-missionswerk-werner-heukelbach\/&#039; title=&#039;Programm-Info&#039; target=&quot;_blank&quot;  rel=&quot;noopener noreferrer&quot;&gt;Programm-Info&lt;\/a&gt;\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" ><a href='https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-missionswerk-werner-heukelbach\/' title='Programm-Info' target=\"_blank\"  rel=\"noopener noreferrer\">Programm-Info<\/a><\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":14014,"parent":4541,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-11827","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.8 (Yoast SEO v24.8.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zeitlose Botschaften - Donnerstag<\/title>\n<meta name=\"description\" content=\"Botschaften zu unterschiedlichen Themen rund um das Leben und den christlichen Glauben.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zeitlose Botschaften - Donnerstag\" \/>\n<meta property=\"og:description\" content=\"Botschaften zu unterschiedlichen Themen rund um das Leben und den christlichen Glauben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/\" \/>\n<meta property=\"og:site_name\" content=\"BBN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BBNGerman\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-20T17:56:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bbn1.bbnradio.org\/german\/wp-content\/uploads\/sites\/9\/2019\/02\/Zeitlose-Botschaften-Missionswerk-Werner-Heukelbach-social.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Zeitlose Botschaften - Donnerstag\" \/>\n<meta name=\"twitter:description\" content=\"Botschaften zu unterschiedlichen Themen rund um das Leben und den christlichen Glauben.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/bbn1.bbnradio.org\/german\/wp-content\/uploads\/sites\/9\/2019\/02\/Zeitlose-Botschaften-Missionswerk-Werner-Heukelbach-social.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@BBNDeutsch\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/\",\"url\":\"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/\",\"name\":\"Zeitlose Botschaften - Donnerstag\",\"isPartOf\":{\"@id\":\"https:\/\/bbn1.bbnradio.org\/german\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bbn1.bbnradio.org\/german\/wp-content\/uploads\/sites\/9\/2019\/02\/Zeitlose-Botschaften-Missionswerk-Werner-Heukelbach.jpg\",\"datePublished\":\"2018-01-08T15:18:49+00:00\",\"dateModified\":\"2019-02-20T17:56:47+00:00\",\"description\":\"Botschaften zu unterschiedlichen Themen rund um das Leben und den christlichen Glauben.\",\"breadcrumb\":{\"@id\":\"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/#primaryimage\",\"url\":\"https:\/\/bbn1.bbnradio.org\/german\/wp-content\/uploads\/sites\/9\/2019\/02\/Zeitlose-Botschaften-Missionswerk-Werner-Heukelbach.jpg\",\"contentUrl\":\"https:\/\/bbn1.bbnradio.org\/german\/wp-content\/uploads\/sites\/9\/2019\/02\/Zeitlose-Botschaften-Missionswerk-Werner-Heukelbach.jpg\",\"width\":1200,\"height\":628,\"caption\":\"Zeitlose Botschaften - Missionswerk Werner Heukelbach\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bbn1.bbnradio.org\/german\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\/\/bbn1.bbnradio.org\/german\/home\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alle Programme\",\"item\":\"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Zeitlose Botschaften &#8211; Donnerstag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bbn1.bbnradio.org\/german\/#website\",\"url\":\"https:\/\/bbn1.bbnradio.org\/german\/\",\"name\":\"BBN\",\"description\":\"BBN\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bbn1.bbnradio.org\/german\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zeitlose Botschaften - Donnerstag","description":"Botschaften zu unterschiedlichen Themen rund um das Leben und den christlichen Glauben.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/","og_locale":"de_DE","og_type":"article","og_title":"Zeitlose Botschaften - Donnerstag","og_description":"Botschaften zu unterschiedlichen Themen rund um das Leben und den christlichen Glauben.","og_url":"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/","og_site_name":"BBN","article_publisher":"https:\/\/www.facebook.com\/BBNGerman\/","article_modified_time":"2019-02-20T17:56:47+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/bbn1.bbnradio.org\/german\/wp-content\/uploads\/sites\/9\/2019\/02\/Zeitlose-Botschaften-Missionswerk-Werner-Heukelbach-social.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Zeitlose Botschaften - Donnerstag","twitter_description":"Botschaften zu unterschiedlichen Themen rund um das Leben und den christlichen Glauben.","twitter_image":"https:\/\/bbn1.bbnradio.org\/german\/wp-content\/uploads\/sites\/9\/2019\/02\/Zeitlose-Botschaften-Missionswerk-Werner-Heukelbach-social.jpg","twitter_site":"@BBNDeutsch","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/","url":"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/","name":"Zeitlose Botschaften - Donnerstag","isPartOf":{"@id":"https:\/\/bbn1.bbnradio.org\/german\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/#primaryimage"},"image":{"@id":"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/#primaryimage"},"thumbnailUrl":"https:\/\/bbn1.bbnradio.org\/german\/wp-content\/uploads\/sites\/9\/2019\/02\/Zeitlose-Botschaften-Missionswerk-Werner-Heukelbach.jpg","datePublished":"2018-01-08T15:18:49+00:00","dateModified":"2019-02-20T17:56:47+00:00","description":"Botschaften zu unterschiedlichen Themen rund um das Leben und den christlichen Glauben.","breadcrumb":{"@id":"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/#primaryimage","url":"https:\/\/bbn1.bbnradio.org\/german\/wp-content\/uploads\/sites\/9\/2019\/02\/Zeitlose-Botschaften-Missionswerk-Werner-Heukelbach.jpg","contentUrl":"https:\/\/bbn1.bbnradio.org\/german\/wp-content\/uploads\/sites\/9\/2019\/02\/Zeitlose-Botschaften-Missionswerk-Werner-Heukelbach.jpg","width":1200,"height":628,"caption":"Zeitlose Botschaften - Missionswerk Werner Heukelbach"},{"@type":"BreadcrumbList","@id":"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/zeitlose-botschaften-donnerstag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bbn1.bbnradio.org\/german\/home\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/bbn1.bbnradio.org\/german\/home\/"},{"@type":"ListItem","position":3,"name":"Alle Programme","item":"https:\/\/bbn1.bbnradio.org\/german\/home\/alle-programme\/"},{"@type":"ListItem","position":4,"name":"Zeitlose Botschaften &#8211; Donnerstag"}]},{"@type":"WebSite","@id":"https:\/\/bbn1.bbnradio.org\/german\/#website","url":"https:\/\/bbn1.bbnradio.org\/german\/","name":"BBN","description":"BBN","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bbn1.bbnradio.org\/german\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PgZlJB-34L","_links":{"self":[{"href":"https:\/\/bbn1.bbnradio.org\/german\/wp-json\/wp\/v2\/pages\/11827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bbn1.bbnradio.org\/german\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bbn1.bbnradio.org\/german\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/german\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/german\/wp-json\/wp\/v2\/comments?post=11827"}],"version-history":[{"count":3,"href":"https:\/\/bbn1.bbnradio.org\/german\/wp-json\/wp\/v2\/pages\/11827\/revisions"}],"predecessor-version":[{"id":14102,"href":"https:\/\/bbn1.bbnradio.org\/german\/wp-json\/wp\/v2\/pages\/11827\/revisions\/14102"}],"up":[{"embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/german\/wp-json\/wp\/v2\/pages\/4541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/german\/wp-json\/wp\/v2\/media\/14014"}],"wp:attachment":[{"href":"https:\/\/bbn1.bbnradio.org\/german\/wp-json\/wp\/v2\/media?parent=11827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/german\/wp-json\/wp\/v2\/categories?post=11827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/german\/wp-json\/wp\/v2\/tags?post=11827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}