{"id":11502,"date":"2018-01-12T10:30:08","date_gmt":"2018-01-12T15:30:08","guid":{"rendered":"http:\/\/bbn1.bbnradio.org\/japanese\/?page_id=11502"},"modified":"2025-07-15T14:47:17","modified_gmt":"2025-07-15T19:47:17","slug":"%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7","status":"publish","type":"page","link":"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/","title":{"rendered":"\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 &#8211; \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b"},"content":{"rendered":"<div id='layer_slider_1'  class='avia-layerslider main_color avia-shadow  avia-builder-el-0  el_before_av_three_fifth  avia-builder-el-first  container_wrap sidebar_right'  style='height: 201px;'  ><\/div><div id='after_layer_slider_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-11502'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-d9qthda-964e4c04b9b1c95ba80280d6c37f3205 av_three_fifth  avia-builder-el-1  el_after_av_layerslider  el_before_av_two_fifth  avia-builder-el-first  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-cm82stq-66cfef5007df011878f5ac1038e29e2a\">\n#top .av-special-heading.av-cm82stq-66cfef5007df011878f5ac1038e29e2a{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-cm82stq-66cfef5007df011878f5ac1038e29e2a .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-cm82stq-66cfef5007df011878f5ac1038e29e2a .av-subheading{\nfont-size:10px;\n}\n<\/style>\n<div  class='av-special-heading av-cm82stq-66cfef5007df011878f5ac1038e29e2a av-special-heading-h3  avia-builder-el-2  el_before_av_image  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-c044e6m-42bd3989f93e098c8324d0d8d54e19eb\">\n.avia-image-container.av-c044e6m-42bd3989f93e098c8324d0d8d54e19eb img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-c044e6m-42bd3989f93e098c8324d0d8d54e19eb .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-c044e6m-42bd3989f93e098c8324d0d8d54e19eb av-styling-no-styling avia_animated_image av-animated-when-visible-95 right-to-left avia-align-left  avia-builder-el-3  el_after_av_heading  el_before_av_textblock '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-12977 avia-img-lazy-loading-not-12977 avia_image ' src=\"https:\/\/i0.wp.com\/bbn1.bbnradio.org\/japanese\/wp-content\/uploads\/sites\/7\/2018\/04\/%E4%BF%A1%E4%BB%B0%E3%83%BB%E3%82%B9%E3%83%86%E3%83%83%E3%83%95%E3%82%9A%E3%82%A2%E3%83%83%E3%83%95%E3%82%9A%EF%BC%81-%E9%85%92%E4%BA%95%E4%BF%A1%E4%B9%9F%EF%BC%88%E3%81%AE%E3%81%B5%E3%82%99%E3%82%84%EF%BC%89%E7%89%A7%E5%B8%AB.jpg?fit=1200%2C628&ssl=1\" alt='\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 - \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b' title='\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d5\u309a\u30a2\u30c3\u30d5\u309a\uff01 - \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3075\u3099\u3084\uff09\u7267\u5e2b'  height=\"628\" width=\"1200\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-bjkmmxa-c9b6f9e2ca8726faf1064e8eed21a3b1 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>\u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b<\/p>\n<\/div><\/section><\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-b2w2p0u-6dc98bc4f786d7df3b436627d496ae44\">\n.flex_column.av-b2w2p0u-6dc98bc4f786d7df3b436627d496ae44{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-b2w2p0u-6dc98bc4f786d7df3b436627d496ae44 av_two_fifth  avia-builder-el-5  el_after_av_three_fifth  el_before_av_heading  flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-as3nhym-059814c53634e9cab4826b79e6ec6add\">\n#top .av-special-heading.av-as3nhym-059814c53634e9cab4826b79e6ec6add{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-as3nhym-059814c53634e9cab4826b79e6ec6add .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-as3nhym-059814c53634e9cab4826b79e6ec6add .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-as3nhym-059814c53634e9cab4826b79e6ec6add av-special-heading-h3 blockquote modern-quote  avia-builder-el-6  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >\u653e\u9001\u6642\u9593<\/h3><div class='av-subheading av-subheading_below'><p>\u6708\u66dc\u65e5\uff5e\u91d1\u66dc\u65e5: 1:00 AM, 3:00 PM, 7:00 PM<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-aga0pla-bfe872e7772dbed9813d875e8a20cc61\">\n#top .hr.av-aga0pla-bfe872e7772dbed9813d875e8a20cc61{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.hr.av-aga0pla-bfe872e7772dbed9813d875e8a20cc61 .hr-inner{\nwidth:100%;\n}\n<\/style>\n<div  class='hr av-aga0pla-bfe872e7772dbed9813d875e8a20cc61 hr-custom  avia-builder-el-7  el_after_av_heading  el_before_av_textblock  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-a0kj77y-467470eb7bfd53faa45cc29dd64a40f2\">\n#top .av_textblock_section.av-a0kj77y-467470eb7bfd53faa45cc29dd64a40f2 .avia_textblock{\nfont-size:20px;\n}\n<\/style>\n<section  class='av_textblock_section av-a0kj77y-467470eb7bfd53faa45cc29dd64a40f2 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: center\">\u73fe\u5728\u653e\u9001\u4e2d<br \/>\n<span id=\"BBN_now_playing\"><\/span><\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9li5b4e-f7c2288282762229cc491d3e65f205ab\">\n#top .hr.hr-invisible.av-9li5b4e-f7c2288282762229cc491d3e65f205ab{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-9li5b4e-f7c2288282762229cc491d3e65f205ab hr-invisible  avia-builder-el-9  el_after_av_textblock  el_before_av_button_big  avia-builder-el-last '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='avia-button-wrap avia-button-center  avia-builder-el-10  el_after_av_hr  avia-builder-el-last '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-8zeuh8u-199db133f8a37a37ce350909a629cf9d\">\n#top #wrap_all .avia-button.av-8zeuh8u-199db133f8a37a37ce350909a629cf9d{\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n#top #wrap_all .avia-button.av-8zeuh8u-199db133f8a37a37ce350909a629cf9d:hover{\nbackground-color:green;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n#top #wrap_all .avia-button.av-8zeuh8u-199db133f8a37a37ce350909a629cf9d .avia-svg-icon svg:first-child{\nfill:#ffffff;\nstroke:#ffffff;\n}\n#top #wrap_all .avia-button.av-8zeuh8u-199db133f8a37a37ce350909a629cf9d:hover .avia-svg-icon svg:first-child{\nfill:#ffffff;\nstroke:#ffffff;\n}\n<\/style>\n<a href='https://\/\/bbn1.bbnradio.org\/japanese\/bbn%e8%81%96%e6%9b%b8%e6%94%be%e9%80%81%e3%82%92%e8%81%b4%e3%81%8f\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa' class='avia-color-theme-color avia-button avia-button-fullwidth av-8zeuh8u-199db133f8a37a37ce350909a629cf9d avia-icon_select-no avia-color-theme-color'  target=\"_blank\"  rel=\"noopener noreferrer\"  aria-label=\"BBN\u3092\u8074\u304f\"><span class='avia_iconbox_title' >BBN\u3092\u8074\u304f<\/span><\/a><\/div><\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-8h1kbn2-776b65f04922cd68cd81e5a0f6cc8688\">\n#top .av-special-heading.av-8h1kbn2-776b65f04922cd68cd81e5a0f6cc8688{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-8h1kbn2-776b65f04922cd68cd81e5a0f6cc8688 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-8h1kbn2-776b65f04922cd68cd81e5a0f6cc8688 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-8h1kbn2-776b65f04922cd68cd81e5a0f6cc8688 av-special-heading-h3 blockquote modern-quote  avia-builder-el-11  el_after_av_two_fifth  el_before_av_one_half '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >\u30aa\u30f3\u30c7\u30de\u30f3\u30c9\u3067\u8074\u304f<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-837y88e-ea4f4584d717cb374486971fd38d74b3\">\n.flex_column.av-837y88e-ea4f4584d717cb374486971fd38d74b3{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-837y88e-ea4f4584d717cb374486971fd38d74b3 av_one_half  avia-builder-el-12  el_after_av_heading  el_before_av_one_half  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7gv8qzy-cc41a9380119e5f7e9f23c048e220e31\">\n#top .avia-icon-list-container.av-7gv8qzy-cc41a9380119e5f7e9f23c048e220e31 .iconlist_icon{\ncolor:#003800;\nbackground-color:#ffffff;\nborder:1px solid #003800;\n}\n#top .avia-icon-list-container.av-7gv8qzy-cc41a9380119e5f7e9f23c048e220e31 .iconlist_icon svg:first-child{\nstroke:#003800;\nfill:#003800;\n}\n<\/style>\n<div  class='avia-icon-list-container av-7gv8qzy-cc41a9380119e5f7e9f23c048e220e31  avia-builder-el-13  avia-builder-el-no-sibling '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-big av-7gv8qzy-cc41a9380119e5f7e9f23c048e220e31 avia-iconlist-animate'>\n<li><a href='https://\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e6%9c%88%e6%9b%9c%e6%97%a5\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa' title='\u6708\u66dc\u65e5'  target=\"_blank\"  rel=\"noopener noreferrer\" class='iconlist_icon av-74mjp0u-8d849f05b5daebf751e74c87231567c0 avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue897' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: &lt;a href=&#039;https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e6%9c%88%e6%9b%9c%e6%97%a5\/&#039; title=&#039;\u6708\u66dc\u65e5&#039; target=&quot;_blank&quot;  rel=&quot;noopener noreferrer&quot;&gt;\u6708\u66dc\u65e5&lt;\/a&gt;\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" ><a href='https://\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e6%9c%88%e6%9b%9c%e6%97%a5\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa' title='\u6708\u66dc\u65e5' target=\"_blank\"  rel=\"noopener noreferrer\">\u6708\u66dc\u65e5<\/a><\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='https://\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e7%81%ab%e6%9b%9c%e6%97%a5\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa' title='\u706b\u66dc\u65e5'  target=\"_blank\"  rel=\"noopener noreferrer\" class='iconlist_icon av-6s11tji-af8a9ae78385f670457712203c22ef9f avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue897' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: &lt;a href=&#039;https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e7%81%ab%e6%9b%9c%e6%97%a5\/&#039; title=&#039;\u706b\u66dc\u65e5&#039; target=&quot;_blank&quot;  rel=&quot;noopener noreferrer&quot;&gt;\u706b\u66dc\u65e5&lt;\/a&gt;\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" ><a href='https://\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e7%81%ab%e6%9b%9c%e6%97%a5\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa' title='\u706b\u66dc\u65e5' target=\"_blank\"  rel=\"noopener noreferrer\">\u706b\u66dc\u65e5<\/a><\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='https://\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e6%b0%b4%e6%9b%9c%e6%97%a5\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa' title='\u6c34\u66dc\u65e5'  target=\"_blank\"  rel=\"noopener noreferrer\" class='iconlist_icon av-68iibpq-8ccbe1ec03feedd3a92a8e2a10ab2287 avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue897' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: &lt;a href=&#039;https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e6%b0%b4%e6%9b%9c%e6%97%a5\/&#039; title=&#039;\u6c34\u66dc\u65e5&#039; target=&quot;_blank&quot;  rel=&quot;noopener noreferrer&quot;&gt;\u6c34\u66dc\u65e5&lt;\/a&gt;\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" ><a href='https://\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e6%b0%b4%e6%9b%9c%e6%97%a5\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa' title='\u6c34\u66dc\u65e5' target=\"_blank\"  rel=\"noopener noreferrer\">\u6c34\u66dc\u65e5<\/a><\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5ybgl9q-5987fe3b3c07d6c281fd787c60414424\">\n.flex_column.av-5ybgl9q-5987fe3b3c07d6c281fd787c60414424{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-5ybgl9q-5987fe3b3c07d6c281fd787c60414424 av_one_half  avia-builder-el-14  el_after_av_one_half  el_before_av_heading  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5hktmr2-a17d5d3e748148d39850b43d55e14493\">\n#top .avia-icon-list-container.av-5hktmr2-a17d5d3e748148d39850b43d55e14493 .iconlist_icon{\ncolor:#003800;\nbackground-color:#ffffff;\nborder:1px solid #003800;\n}\n#top .avia-icon-list-container.av-5hktmr2-a17d5d3e748148d39850b43d55e14493 .iconlist_icon svg:first-child{\nstroke:#003800;\nfill:#003800;\n}\n<\/style>\n<div  class='avia-icon-list-container av-5hktmr2-a17d5d3e748148d39850b43d55e14493  avia-builder-el-15  avia-builder-el-no-sibling '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-big av-5hktmr2-a17d5d3e748148d39850b43d55e14493 avia-iconlist-animate'>\n<li><a href='https://\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e6%9c%a8%e6%9b%9c%e6%97%a5\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa' title='\u6728\u66dc\u65e5'  target=\"_blank\"  rel=\"noopener noreferrer\" class='iconlist_icon av-4zkefta-c53a796069b66dadfb0afcf4e0f9ecd0 avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue897' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: &lt;a href=&#039;https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e6%9c%a8%e6%9b%9c%e6%97%a5\/&#039; title=&#039;\u6728\u66dc\u65e5&#039; target=&quot;_blank&quot;  rel=&quot;noopener noreferrer&quot;&gt;\u6728\u66dc\u65e5&lt;\/a&gt;\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" ><a href='https://\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e6%9c%a8%e6%9b%9c%e6%97%a5\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa' title='\u6728\u66dc\u65e5' target=\"_blank\"  rel=\"noopener noreferrer\">\u6728\u66dc\u65e5<\/a><\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='https://\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%87%91%e6%9b%9c%e6%97%a5\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa' title='\u91d1\u66dc\u65e5'  target=\"_blank\"  rel=\"noopener noreferrer\" class='iconlist_icon av-4hcpram-54dd13c3d6452de317bac81af2e8b269 avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue897' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: &lt;a href=&#039;https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%87%91%e6%9b%9c%e6%97%a5\/&#039; title=&#039;\u91d1\u66dc\u65e5&#039; target=&quot;_blank&quot;  rel=&quot;noopener noreferrer&quot;&gt;\u91d1\u66dc\u65e5&lt;\/a&gt;\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" ><a href='https://\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%87%91%e6%9b%9c%e6%97%a5\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa' title='\u91d1\u66dc\u65e5' target=\"_blank\"  rel=\"noopener noreferrer\">\u91d1\u66dc\u65e5<\/a><\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><a href='https://\/\/bbn1.bbnradio.org\/japanese\/bbn%e8%81%96%e6%9b%b8%e6%94%be%e9%80%81%e3%82%92%e8%81%b4%e3%81%8f\/bbn%e3%82%a2%e3%83%97%e3%83%aa\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa' title='BBN\u30a2\u30d7\u30ea'  target=\"_blank\"  rel=\"noopener noreferrer\" class='iconlist_icon av-3unmgoe-084ce5308919fa0d9bea9f1d2affeb2b avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue86f' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/a><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: &lt;a href=&#039;https:\/\/bbn1.bbnradio.org\/japanese\/bbn%e8%81%96%e6%9b%b8%e6%94%be%e9%80%81%e3%82%92%e8%81%b4%e3%81%8f\/bbn%e3%82%a2%e3%83%97%e3%83%aa\/&#039; title=&#039;BBN\u30a2\u30d7\u30ea&#039; target=&quot;_blank&quot;  rel=&quot;noopener noreferrer&quot;&gt;BBN\u30a2\u30d7\u30ea&lt;\/a&gt;\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" ><a href='https://\/\/bbn1.bbnradio.org\/japanese\/bbn%e8%81%96%e6%9b%b8%e6%94%be%e9%80%81%e3%82%92%e8%81%b4%e3%81%8f\/bbn%e3%82%a2%e3%83%97%e3%83%aa\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa' title='BBN\u30a2\u30d7\u30ea' target=\"_blank\"  rel=\"noopener noreferrer\">BBN\u30a2\u30d7\u30ea<\/a><\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><p>iPhone\u3084\u30a2\u30f3\u30c9\u30ed\u30a4\u30c9\u7aef\u672b\u3001\u30a2\u30de\u30be\u30f3\u3001Windows Phone\u3001Roku\u306a\u3069\u306eBBN\u30a2\u30d7\u30ea\u3092\u3054\u5229\u7528\u304f\u3060\u3055\u3044\u3002<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3o97pke-d71d595df145d2186aa32c012f96ae6a\">\n#top .av-special-heading.av-3o97pke-d71d595df145d2186aa32c012f96ae6a{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-3o97pke-d71d595df145d2186aa32c012f96ae6a .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-3o97pke-d71d595df145d2186aa32c012f96ae6a .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-3o97pke-d71d595df145d2186aa32c012f96ae6a av-special-heading-h3 blockquote modern-quote  avia-builder-el-16  el_after_av_one_half  el_before_av_textblock '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >\u756a\u7d44\u7d39\u4ecb<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<section  class='av_textblock_section av-33e13m6-61b57d4d9a2cb8cf074cb47879d5d31c '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>\u300c\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01\u300d\u306f\u3001\u9152\u4e95\u4fe1\u4e5f\uff08\u3055\u304b\u3044\u306e\u3076\u3084\uff09\u7267\u5e2b\u306e\u30e1\u30c3\u30bb\u30fc\u30b8\u756a\u7d44\u3067\u3059\u3002\u9152\u4e95\u7267\u5e2b\u306f\u3001\u5ba3\u6559\u56e3\u4f53OM\u306e\u65e5\u672c\u7dcf\u4e3b\u4e8b\u3068\u3057\u3066\u3001\u4e16\u754c\u5ba3\u6559\u306b\u643a\u308f\u308a\u30012011\u5e744\u6708\u304b\u3089\u5185\u7058\u8056\u66f8\u6559\u4f1a\u306e\u4e3b\u4efb\u7267\u5e2b\u3068\u3057\u3066\u304a\u4ed5\u3048\u3057\u3066\u3044\u307e\u3059\u3002<\/p>\n<p>\u6df7\u3068\u3093\u3068\u3057\u305f\u73fe\u4ee3\u306b\u751f\u304d\u308b\u79c1\u305f\u3061\u304c\u3001\u4e16\u306e\u4fa1\u5024\u89b3\u306b\u60d1\u308f\u3055\u308c\u308b\u3053\u3068\u306a\u304f\u4fe1\u4ef0\u3092\u4fdd\u3064\u306e\u306f\u3001\u78ba\u304b\u306b\u5927\u5909\u3002\u3069\u3046\u305e\u3001\u756a\u7d44\u3092\u901a\u3057\u3066\u30a4\u30a8\u30b9\u30fb\u30ad\u30ea\u30b9\u30c8\u306b\u3042\u308b\u4fe1\u4ef0\u3092\u78ba\u4fe1\u3057\u3001\u529b\u3068\u5e0c\u671b\u3092\u795e\u69d8\u304b\u3089\u9802\u3044\u3066\u4e0b\u3055\u3044\u3002\u6bce\u56de\u3001\u9152\u4e95\u7267\u5e2b\u304c\u3001\u79c1\u305f\u3061\u306e\u4fe1\u4ef0\u306e\u6210\u9577\u306e\u305f\u3081\u306b\u5fc3\u306b\u7559\u3081\u3066\u304a\u304d\u305f\u3044\u3053\u3068\u304c\u3089\u3092\u3001\u307f\u3053\u3068\u3070\u304b\u3089\u5206\u304b\u308a\u3084\u3059\u304f\u304a\u8a71\u3057\u307e\u3059\u3002\u82e5\u3044\u65b9\u3005\u304b\u3089\u5e74\u914d\u306e\u65b9\u307e\u3067\u3001\u5e45\u5e83\u304f\u8074\u3044\u3066\u9802\u3051\u307e\u3059\u3002<\/p>\n<h3><\/h3>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2dtrdv2-13a4c60bd87ad0d9dc27cb1f24becd4e\">\n#top .av-special-heading.av-2dtrdv2-13a4c60bd87ad0d9dc27cb1f24becd4e{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-2dtrdv2-13a4c60bd87ad0d9dc27cb1f24becd4e .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-2dtrdv2-13a4c60bd87ad0d9dc27cb1f24becd4e .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-2dtrdv2-13a4c60bd87ad0d9dc27cb1f24becd4e av-special-heading-h3 blockquote modern-quote  avia-builder-el-18  el_after_av_textblock  el_before_av_textblock '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >\u3053\u306e\u756a\u7d44\u306fBBN\u304c\u5236\u4f5c\u3057\u3066\u3044\u307e\u3059\u3002<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<section  class='av_textblock_section av-23b7zfy-f38de8a439519f819226ae1a35d57028 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>\u795e\u69d8\u306f\u30ea\u30b9\u30ca\u30fc\u306e\u6e29\u304b\u3044\u30b5\u30dd\u30fc\u30c8\u3092\u901a\u3057\u3066BBN\u306e\u7d4c\u6e08\u7684\u5fc5\u8981\u3092\u6e80\u305f\u3057\u3066\u304f\u3060\u3055\u3063\u3066\u3044\u307e\u3059\u3002\u3053\u306e\u732e\u91d1\u306e\u50cd\u304d\u306f\u30ac\u30e9\u30c6\u30e4\u4eba\u3078\u306e\u624b\u7d196\uff1a6\u306b\u57fa\u3065\u304f\u3082\u306e\u3067\u3001\u00a0\u3042\u306a\u305f\u306e\u732e\u91d1\u306f\u756a\u7d44\u63d0\u4f9b\u8005\u306b\u653e\u9001\u6599\u91d1\u3092\u8acb\u6c42\u3059\u308b\u3053\u3068\u306a\u304f\u300c\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01\u300d\u306e\u3088\u3046\u306a\u3059\u3070\u3089\u3057\u3044\u756a\u7d44\u3092\u653e\u9001\u3057\u3001\u4eba\u3005\u306b\u30a4\u30a8\u30b9\u30fb\u30ad\u30ea\u30b9\u30c8\u3092\u7d39\u4ecb\u3059\u308b\u624b\u52a9\u3051\u3068\u306a\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\n<\/div><\/section>\n<div  class='avia-button-wrap av-1m7q29a-444b140f7f463e52ca4dee6e9a841bae-wrap avia-button-left  avia-builder-el-20  el_after_av_textblock  el_before_av_heading '><a href='https://\/\/bbn1.bbnradio.org\/japanese\/bbn%e3%81%b8%e3%81%ae%e7%8c%ae%e9%87%91\/?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa'  class='avia-button av-1m7q29a-444b140f7f463e52ca4dee6e9a841bae av-link-btn avia-icon_select-no avia-size-x-large avia-position-left avia-color-theme-color'   aria-label=\"BBN\u306b\u732e\u91d1\u3059\u308b\"><span class='avia_iconbox_title' >BBN\u306b\u732e\u91d1\u3059\u308b<\/span><\/a><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1clmsb2-8a8329785e1234836275b26cf785e511\">\n#top .av-special-heading.av-1clmsb2-8a8329785e1234836275b26cf785e511{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-1clmsb2-8a8329785e1234836275b26cf785e511 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-1clmsb2-8a8329785e1234836275b26cf785e511 .av-subheading{\nfont-size:10px;\n}\n<\/style>\n<div  class='av-special-heading av-1clmsb2-8a8329785e1234836275b26cf785e511 av-special-heading-h3 blockquote modern-quote  avia-builder-el-21  el_after_av_button  el_before_av_textblock '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >\u30ea\u30bd\u30fc\u30b9<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<section  class='av_textblock_section av-vvvz72-60ac2b7ae8e3023d805830c97b87cd05 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><ul>\n<li style=\"list-style-type: none\">\n<ul>\n<li><a href=\?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e8%81%96%e6%9b%b8%e6%94%be%e9%80%81%e3%82%ab%e3%83%86%e3%82%b4%e3%83%aa\/%e3%83%87%e3%83%9c%e3%83%bc%e3%82%b7%e3%83%a7%e3%83%b3%e7%95%aa%e7%b5%84\/\">\u30c7\u30dc\u30fc\u30b7\u30e7\u30f3\u306b\u95a2\u3059\u308b\u756a\u7d44<\/a><\/li>\n<li><a href=\?PHPSESSID=pP4yrO9EI2zMe6u2jizi1k5N7qckPCfa"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e8%81%96%e6%9b%b8%e6%94%be%e9%80%81%e3%82%ab%e3%83%86%e3%82%b4%e3%83%aa\/%e8%81%96%e6%9b%b8%e3%81%ae%e6%95%99%e3%81%88\/\">\u8056\u66f8\u306e\u6559\u3048\u306b\u95a2\u3059\u308b\u756a\u7d44<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div><\/section>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":12977,"parent":4541,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false,"footnotes":""},"categories":[2,8,9,15],"tags":[],"class_list":["post-11502","page","type-page","status-publish","has-post-thumbnail","hentry","category-bbn-program-main-page","category-program-category-bible-teaching","category-program-category-devotional","category-program-category-on-demand"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.8 (Yoast SEO v24.8.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 - \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b<\/title>\n<meta name=\"description\" content=\"\u300c\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01\u300d\u306f\u3001\u9152\u4e95\u4fe1\u4e5f\uff08\u3055\u304b\u3044\u306e\u3076\u3084\uff09\u7267\u5e2b\u306e\u30e1\u30c3\u30bb\u30fc\u30b8\u756a\u7d44\u3067\u3059 \u3002\u6bce\u56de\u3001\u9152\u4e95\u7267\u5e2b\u304c\u3001\u79c1\u305f\u3061\u306e\u4fe1\u4ef0\u306e\u6210\u9577\u306e\u305f\u3081\u306b\u5fc3\u306b\u7559\u3081\u3066\u304a\u304d\u305f\u3044\u3053\u3068\u304c\u3089\u3092\u3001\u307f\u3053\u3068\u3070\u304b\u3089\u5206\u304b\u308a\u3084\u3059\u304f\u304a\u8a71\u3057\u307e\u3059\u3002\u82e5\u3044\u65b9\u3005\u304b\u3089\u5e74\u914d\u306e\u65b9\u307e\u3067\u3001\u5e45\u5e83\u304f\u8074\u3044\u3066\u9802\u3051\u307e\u3059\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bbn1.bbnradio.org\/japanese\/\u5bb6\u65cf\u307f\u3093\u306a\u306e\u30af\u30ea\u30b9\u30c1\u30e3\u30f3\u30fb\u30e9\u30b8\u30aa\u653e\u9001\u5c40\u300cbbn\u8056\/bbn\u3067\u304a\u5c4a\u3051\u3057\u3066\u3044\u308b\u756a\u7d44\/\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01-\u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 - \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b\" \/>\n<meta property=\"og:description\" content=\"\u300c\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01\u300d\u306f\u3001\u9152\u4e95\u4fe1\u4e5f\uff08\u3055\u304b\u3044\u306e\u3076\u3084\uff09\u7267\u5e2b\u306e\u30e1\u30c3\u30bb\u30fc\u30b8\u756a\u7d44\u3067\u3059 \u3002\u6bce\u56de\u3001\u9152\u4e95\u7267\u5e2b\u304c\u3001\u79c1\u305f\u3061\u306e\u4fe1\u4ef0\u306e\u6210\u9577\u306e\u305f\u3081\u306b\u5fc3\u306b\u7559\u3081\u3066\u304a\u304d\u305f\u3044\u3053\u3068\u304c\u3089\u3092\u3001\u307f\u3053\u3068\u3070\u304b\u3089\u5206\u304b\u308a\u3084\u3059\u304f\u304a\u8a71\u3057\u307e\u3059\u3002\u82e5\u3044\u65b9\u3005\u304b\u3089\u5e74\u914d\u306e\u65b9\u307e\u3067\u3001\u5e45\u5e83\u304f\u8074\u3044\u3066\u9802\u3051\u307e\u3059\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bbn1.bbnradio.org\/japanese\/\u5bb6\u65cf\u307f\u3093\u306a\u306e\u30af\u30ea\u30b9\u30c1\u30e3\u30f3\u30fb\u30e9\u30b8\u30aa\u653e\u9001\u5c40\u300cbbn\u8056\/bbn\u3067\u304a\u5c4a\u3051\u3057\u3066\u3044\u308b\u756a\u7d44\/\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01-\u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\/\" \/>\n<meta property=\"og:site_name\" content=\"BBN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BBNJapanese\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-15T19:47:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/bbn1.bbnradio.org\/japanese\/wp-content\/uploads\/sites\/7\/2018\/04\/\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d5\u309a\u30a2\u30c3\u30d5\u309a\uff01-\u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3075\u3099\u3084\uff09\u7267\u5e2b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 - \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b\" \/>\n<meta name=\"twitter:description\" content=\"\u300c\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01\u300d\u306f\u3001\u9152\u4e95\u4fe1\u4e5f\uff08\u3055\u304b\u3044\u306e\u3076\u3084\uff09\u7267\u5e2b\u306e\u30e1\u30c3\u30bb\u30fc\u30b8\u756a\u7d44\u3067\u3059 \u3002\u6bce\u56de\u3001\u9152\u4e95\u7267\u5e2b\u304c\u3001\u79c1\u305f\u3061\u306e\u4fe1\u4ef0\u306e\u6210\u9577\u306e\u305f\u3081\u306b\u5fc3\u306b\u7559\u3081\u3066\u304a\u304d\u305f\u3044\u3053\u3068\u304c\u3089\u3092\u3001\u307f\u3053\u3068\u3070\u304b\u3089\u5206\u304b\u308a\u3084\u3059\u304f\u304a\u8a71\u3057\u307e\u3059\u3002\u82e5\u3044\u65b9\u3005\u304b\u3089\u5e74\u914d\u306e\u65b9\u307e\u3067\u3001\u5e45\u5e83\u304f\u8074\u3044\u3066\u9802\u3051\u307e\u3059\u3002\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/i0.wp.com\/bbn1.bbnradio.org\/japanese\/wp-content\/uploads\/sites\/7\/2018\/04\/%E4%BF%A1%E4%BB%B0%E3%83%BB%E3%82%B9%E3%83%86%E3%83%83%E3%83%95%E3%82%9A%E3%82%A2%E3%83%83%E3%83%95%E3%82%9A%EF%BC%81-%E9%85%92%E4%BA%95%E4%BF%A1%E4%B9%9F%EF%BC%88%E3%81%AE%E3%81%B5%E3%82%99%E3%82%84%EF%BC%89%E7%89%A7%E5%B8%AB.jpg?fit=1200%2C628&ssl=1\" \/>\n<meta name=\"twitter:site\" content=\"@BBNJapanese\" \/>\n<meta name=\"twitter:label1\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"17\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/\",\"url\":\"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/\",\"name\":\"\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 - \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b\",\"isPartOf\":{\"@id\":\"https:\/\/bbn1.bbnradio.org\/japanese\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/bbn1.bbnradio.org\/japanese\/wp-content\/uploads\/sites\/7\/2018\/04\/%E4%BF%A1%E4%BB%B0%E3%83%BB%E3%82%B9%E3%83%86%E3%83%83%E3%83%95%E3%82%9A%E3%82%A2%E3%83%83%E3%83%95%E3%82%9A%EF%BC%81-%E9%85%92%E4%BA%95%E4%BF%A1%E4%B9%9F%EF%BC%88%E3%81%AE%E3%81%B5%E3%82%99%E3%82%84%EF%BC%89%E7%89%A7%E5%B8%AB.jpg?fit=1200%2C628&ssl=1\",\"datePublished\":\"2018-01-12T15:30:08+00:00\",\"dateModified\":\"2025-07-15T19:47:17+00:00\",\"description\":\"\u300c\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01\u300d\u306f\u3001\u9152\u4e95\u4fe1\u4e5f\uff08\u3055\u304b\u3044\u306e\u3076\u3084\uff09\u7267\u5e2b\u306e\u30e1\u30c3\u30bb\u30fc\u30b8\u756a\u7d44\u3067\u3059 \u3002\u6bce\u56de\u3001\u9152\u4e95\u7267\u5e2b\u304c\u3001\u79c1\u305f\u3061\u306e\u4fe1\u4ef0\u306e\u6210\u9577\u306e\u305f\u3081\u306b\u5fc3\u306b\u7559\u3081\u3066\u304a\u304d\u305f\u3044\u3053\u3068\u304c\u3089\u3092\u3001\u307f\u3053\u3068\u3070\u304b\u3089\u5206\u304b\u308a\u3084\u3059\u304f\u304a\u8a71\u3057\u307e\u3059\u3002\u82e5\u3044\u65b9\u3005\u304b\u3089\u5e74\u914d\u306e\u65b9\u307e\u3067\u3001\u5e45\u5e83\u304f\u8074\u3044\u3066\u9802\u3051\u307e\u3059\u3002\",\"breadcrumb\":{\"@id\":\"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/bbn1.bbnradio.org\/japanese\/wp-content\/uploads\/sites\/7\/2018\/04\/%E4%BF%A1%E4%BB%B0%E3%83%BB%E3%82%B9%E3%83%86%E3%83%83%E3%83%95%E3%82%9A%E3%82%A2%E3%83%83%E3%83%95%E3%82%9A%EF%BC%81-%E9%85%92%E4%BA%95%E4%BF%A1%E4%B9%9F%EF%BC%88%E3%81%AE%E3%81%B5%E3%82%99%E3%82%84%EF%BC%89%E7%89%A7%E5%B8%AB.jpg?fit=1200%2C628&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/bbn1.bbnradio.org\/japanese\/wp-content\/uploads\/sites\/7\/2018\/04\/%E4%BF%A1%E4%BB%B0%E3%83%BB%E3%82%B9%E3%83%86%E3%83%83%E3%83%95%E3%82%9A%E3%82%A2%E3%83%83%E3%83%95%E3%82%9A%EF%BC%81-%E9%85%92%E4%BA%95%E4%BF%A1%E4%B9%9F%EF%BC%88%E3%81%AE%E3%81%B5%E3%82%99%E3%82%84%EF%BC%89%E7%89%A7%E5%B8%AB.jpg?fit=1200%2C628&ssl=1\",\"width\":1200,\"height\":628,\"caption\":\"\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 - \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u5bb6\u65cf\u307f\u3093\u306a\u306e\u30af\u30ea\u30b9\u30c1\u30e3\u30f3\u30fb\u30e9\u30b8\u30aa\u653e\u9001\u5c40\u300cBBN\u8056\u66f8\u653e\u9001\u300d\",\"item\":\"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BBN\u3067\u304a\u5c4a\u3051\u3057\u3066\u3044\u308b\u756a\u7d44\",\"item\":\"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 &#8211; \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bbn1.bbnradio.org\/japanese\/#website\",\"url\":\"https:\/\/bbn1.bbnradio.org\/japanese\/\",\"name\":\"BBN Japanese\",\"description\":\"BBN\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bbn1.bbnradio.org\/japanese\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 - \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b","description":"\u300c\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01\u300d\u306f\u3001\u9152\u4e95\u4fe1\u4e5f\uff08\u3055\u304b\u3044\u306e\u3076\u3084\uff09\u7267\u5e2b\u306e\u30e1\u30c3\u30bb\u30fc\u30b8\u756a\u7d44\u3067\u3059 \u3002\u6bce\u56de\u3001\u9152\u4e95\u7267\u5e2b\u304c\u3001\u79c1\u305f\u3061\u306e\u4fe1\u4ef0\u306e\u6210\u9577\u306e\u305f\u3081\u306b\u5fc3\u306b\u7559\u3081\u3066\u304a\u304d\u305f\u3044\u3053\u3068\u304c\u3089\u3092\u3001\u307f\u3053\u3068\u3070\u304b\u3089\u5206\u304b\u308a\u3084\u3059\u304f\u304a\u8a71\u3057\u307e\u3059\u3002\u82e5\u3044\u65b9\u3005\u304b\u3089\u5e74\u914d\u306e\u65b9\u307e\u3067\u3001\u5e45\u5e83\u304f\u8074\u3044\u3066\u9802\u3051\u307e\u3059\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bbn1.bbnradio.org\/japanese\/\u5bb6\u65cf\u307f\u3093\u306a\u306e\u30af\u30ea\u30b9\u30c1\u30e3\u30f3\u30fb\u30e9\u30b8\u30aa\u653e\u9001\u5c40\u300cbbn\u8056\/bbn\u3067\u304a\u5c4a\u3051\u3057\u3066\u3044\u308b\u756a\u7d44\/\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01-\u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\/","og_locale":"ja_JP","og_type":"article","og_title":"\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 - \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b","og_description":"\u300c\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01\u300d\u306f\u3001\u9152\u4e95\u4fe1\u4e5f\uff08\u3055\u304b\u3044\u306e\u3076\u3084\uff09\u7267\u5e2b\u306e\u30e1\u30c3\u30bb\u30fc\u30b8\u756a\u7d44\u3067\u3059 \u3002\u6bce\u56de\u3001\u9152\u4e95\u7267\u5e2b\u304c\u3001\u79c1\u305f\u3061\u306e\u4fe1\u4ef0\u306e\u6210\u9577\u306e\u305f\u3081\u306b\u5fc3\u306b\u7559\u3081\u3066\u304a\u304d\u305f\u3044\u3053\u3068\u304c\u3089\u3092\u3001\u307f\u3053\u3068\u3070\u304b\u3089\u5206\u304b\u308a\u3084\u3059\u304f\u304a\u8a71\u3057\u307e\u3059\u3002\u82e5\u3044\u65b9\u3005\u304b\u3089\u5e74\u914d\u306e\u65b9\u307e\u3067\u3001\u5e45\u5e83\u304f\u8074\u3044\u3066\u9802\u3051\u307e\u3059\u3002","og_url":"https:\/\/bbn1.bbnradio.org\/japanese\/\u5bb6\u65cf\u307f\u3093\u306a\u306e\u30af\u30ea\u30b9\u30c1\u30e3\u30f3\u30fb\u30e9\u30b8\u30aa\u653e\u9001\u5c40\u300cbbn\u8056\/bbn\u3067\u304a\u5c4a\u3051\u3057\u3066\u3044\u308b\u756a\u7d44\/\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01-\u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\/","og_site_name":"BBN","article_publisher":"https:\/\/www.facebook.com\/BBNJapanese\/","article_modified_time":"2025-07-15T19:47:17+00:00","og_image":[{"width":1200,"height":628,"url":"http:\/\/bbn1.bbnradio.org\/japanese\/wp-content\/uploads\/sites\/7\/2018\/04\/\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d5\u309a\u30a2\u30c3\u30d5\u309a\uff01-\u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3075\u3099\u3084\uff09\u7267\u5e2b.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 - \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b","twitter_description":"\u300c\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01\u300d\u306f\u3001\u9152\u4e95\u4fe1\u4e5f\uff08\u3055\u304b\u3044\u306e\u3076\u3084\uff09\u7267\u5e2b\u306e\u30e1\u30c3\u30bb\u30fc\u30b8\u756a\u7d44\u3067\u3059 \u3002\u6bce\u56de\u3001\u9152\u4e95\u7267\u5e2b\u304c\u3001\u79c1\u305f\u3061\u306e\u4fe1\u4ef0\u306e\u6210\u9577\u306e\u305f\u3081\u306b\u5fc3\u306b\u7559\u3081\u3066\u304a\u304d\u305f\u3044\u3053\u3068\u304c\u3089\u3092\u3001\u307f\u3053\u3068\u3070\u304b\u3089\u5206\u304b\u308a\u3084\u3059\u304f\u304a\u8a71\u3057\u307e\u3059\u3002\u82e5\u3044\u65b9\u3005\u304b\u3089\u5e74\u914d\u306e\u65b9\u307e\u3067\u3001\u5e45\u5e83\u304f\u8074\u3044\u3066\u9802\u3051\u307e\u3059\u3002","twitter_image":"https:\/\/i0.wp.com\/bbn1.bbnradio.org\/japanese\/wp-content\/uploads\/sites\/7\/2018\/04\/%E4%BF%A1%E4%BB%B0%E3%83%BB%E3%82%B9%E3%83%86%E3%83%83%E3%83%95%E3%82%9A%E3%82%A2%E3%83%83%E3%83%95%E3%82%9A%EF%BC%81-%E9%85%92%E4%BA%95%E4%BF%A1%E4%B9%9F%EF%BC%88%E3%81%AE%E3%81%B5%E3%82%99%E3%82%84%EF%BC%89%E7%89%A7%E5%B8%AB.jpg?fit=1200%2C628&ssl=1","twitter_site":"@BBNJapanese","twitter_misc":{"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"17\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/","url":"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/","name":"\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 - \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b","isPartOf":{"@id":"https:\/\/bbn1.bbnradio.org\/japanese\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/#primaryimage"},"image":{"@id":"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/bbn1.bbnradio.org\/japanese\/wp-content\/uploads\/sites\/7\/2018\/04\/%E4%BF%A1%E4%BB%B0%E3%83%BB%E3%82%B9%E3%83%86%E3%83%83%E3%83%95%E3%82%9A%E3%82%A2%E3%83%83%E3%83%95%E3%82%9A%EF%BC%81-%E9%85%92%E4%BA%95%E4%BF%A1%E4%B9%9F%EF%BC%88%E3%81%AE%E3%81%B5%E3%82%99%E3%82%84%EF%BC%89%E7%89%A7%E5%B8%AB.jpg?fit=1200%2C628&ssl=1","datePublished":"2018-01-12T15:30:08+00:00","dateModified":"2025-07-15T19:47:17+00:00","description":"\u300c\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01\u300d\u306f\u3001\u9152\u4e95\u4fe1\u4e5f\uff08\u3055\u304b\u3044\u306e\u3076\u3084\uff09\u7267\u5e2b\u306e\u30e1\u30c3\u30bb\u30fc\u30b8\u756a\u7d44\u3067\u3059 \u3002\u6bce\u56de\u3001\u9152\u4e95\u7267\u5e2b\u304c\u3001\u79c1\u305f\u3061\u306e\u4fe1\u4ef0\u306e\u6210\u9577\u306e\u305f\u3081\u306b\u5fc3\u306b\u7559\u3081\u3066\u304a\u304d\u305f\u3044\u3053\u3068\u304c\u3089\u3092\u3001\u307f\u3053\u3068\u3070\u304b\u3089\u5206\u304b\u308a\u3084\u3059\u304f\u304a\u8a71\u3057\u307e\u3059\u3002\u82e5\u3044\u65b9\u3005\u304b\u3089\u5e74\u914d\u306e\u65b9\u307e\u3067\u3001\u5e45\u5e83\u304f\u8074\u3044\u3066\u9802\u3051\u307e\u3059\u3002","breadcrumb":{"@id":"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/#primaryimage","url":"https:\/\/i0.wp.com\/bbn1.bbnradio.org\/japanese\/wp-content\/uploads\/sites\/7\/2018\/04\/%E4%BF%A1%E4%BB%B0%E3%83%BB%E3%82%B9%E3%83%86%E3%83%83%E3%83%95%E3%82%9A%E3%82%A2%E3%83%83%E3%83%95%E3%82%9A%EF%BC%81-%E9%85%92%E4%BA%95%E4%BF%A1%E4%B9%9F%EF%BC%88%E3%81%AE%E3%81%B5%E3%82%99%E3%82%84%EF%BC%89%E7%89%A7%E5%B8%AB.jpg?fit=1200%2C628&ssl=1","contentUrl":"https:\/\/i0.wp.com\/bbn1.bbnradio.org\/japanese\/wp-content\/uploads\/sites\/7\/2018\/04\/%E4%BF%A1%E4%BB%B0%E3%83%BB%E3%82%B9%E3%83%86%E3%83%83%E3%83%95%E3%82%9A%E3%82%A2%E3%83%83%E3%83%95%E3%82%9A%EF%BC%81-%E9%85%92%E4%BA%95%E4%BF%A1%E4%B9%9F%EF%BC%88%E3%81%AE%E3%81%B5%E3%82%99%E3%82%84%EF%BC%89%E7%89%A7%E5%B8%AB.jpg?fit=1200%2C628&ssl=1","width":1200,"height":628,"caption":"\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 - \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b"},{"@type":"BreadcrumbList","@id":"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/%e4%bf%a1%e4%bb%b0%e3%83%bb%e3%82%b9%e3%83%86%e3%83%83%e3%83%97%e3%82%a2%e3%83%83%e3%83%97%ef%bc%81-%e9%85%92%e4%ba%95%e4%bf%a1%e4%b9%9f%ef%bc%88%e3%81%ae%e3%81%b6%e3%82%84%ef%bc%89%e7%89%a7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/"},{"@type":"ListItem","position":2,"name":"\u5bb6\u65cf\u307f\u3093\u306a\u306e\u30af\u30ea\u30b9\u30c1\u30e3\u30f3\u30fb\u30e9\u30b8\u30aa\u653e\u9001\u5c40\u300cBBN\u8056\u66f8\u653e\u9001\u300d","item":"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/"},{"@type":"ListItem","position":3,"name":"BBN\u3067\u304a\u5c4a\u3051\u3057\u3066\u3044\u308b\u756a\u7d44","item":"https:\/\/bbn1.bbnradio.org\/japanese\/%e5%ae%b6%e6%97%8f%e3%81%bf%e3%82%93%e3%81%aa%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%81%e3%83%a3%e3%83%b3%e3%83%bb%e3%83%a9%e3%82%b8%e3%82%aa%e6%94%be%e9%80%81%e5%b1%80%e3%80%8cbbn%e8%81%96\/bbn%e3%81%a7%e3%81%8a%e5%b1%8a%e3%81%91%e3%81%97%e3%81%a6%e3%81%84%e3%82%8b%e7%95%aa%e7%b5%84\/"},{"@type":"ListItem","position":4,"name":"\u4fe1\u4ef0\u30fb\u30b9\u30c6\u30c3\u30d7\u30a2\u30c3\u30d7\uff01 &#8211; \u9152\u4e95\u4fe1\u4e5f\uff08\u306e\u3076\u3084\uff09\u7267\u5e2b"}]},{"@type":"WebSite","@id":"https:\/\/bbn1.bbnradio.org\/japanese\/#website","url":"https:\/\/bbn1.bbnradio.org\/japanese\/","name":"BBN Japanese","description":"BBN","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bbn1.bbnradio.org\/japanese\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/P85nPc-2Zw","_links":{"self":[{"href":"https:\/\/bbn1.bbnradio.org\/japanese\/wp-json\/wp\/v2\/pages\/11502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bbn1.bbnradio.org\/japanese\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bbn1.bbnradio.org\/japanese\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/japanese\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/japanese\/wp-json\/wp\/v2\/comments?post=11502"}],"version-history":[{"count":3,"href":"https:\/\/bbn1.bbnradio.org\/japanese\/wp-json\/wp\/v2\/pages\/11502\/revisions"}],"predecessor-version":[{"id":15223,"href":"https:\/\/bbn1.bbnradio.org\/japanese\/wp-json\/wp\/v2\/pages\/11502\/revisions\/15223"}],"up":[{"embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/japanese\/wp-json\/wp\/v2\/pages\/4541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/japanese\/wp-json\/wp\/v2\/media\/12977"}],"wp:attachment":[{"href":"https:\/\/bbn1.bbnradio.org\/japanese\/wp-json\/wp\/v2\/media?parent=11502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/japanese\/wp-json\/wp\/v2\/categories?post=11502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/japanese\/wp-json\/wp\/v2\/tags?post=11502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}