{"id":3968,"date":"2015-06-18T11:37:20","date_gmt":"2015-06-18T15:37:20","guid":{"rendered":"https:\/\/bbn1.bbnradio.org\/english\/?page_id=3968"},"modified":"2018-05-03T08:18:40","modified_gmt":"2018-05-03T13:18:40","slug":"%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac%e5%85%b3%e4%ba%8e%e5%a5%89%e7%8c%ae","status":"publish","type":"page","link":"https:\/\/bbn1.bbnradio.org\/schinese\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac%e5%85%b3%e4%ba%8e%e5%a5%89%e7%8c%ae\/","title":{"rendered":"\u8054\u7edc\u6211\u4eec\u5173\u4e8e\u5949\u732e"},"content":{"rendered":"<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" >\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3967-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/schinese\/wp-json\/wp\/v2\/pages\/3968#wpcf7-f3967-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"3967\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.7.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3967-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p>\u4f60\u7684\u59d3\u540d\uff08\u5fc5\u586b\uff09\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"25\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p>\u7535\u90ae\u5730\u5740\uff08\u5fc5\u586b\uff09\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p>\u7535\u8bdd\u53f7\u7801\uff08\u5fc5\u586b\uff09\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-118\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-118\" \/><\/span>\n<\/p>\n<p>\u5730\u5740\uff08\u5fc5\u586b\uff09\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-584\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"textarea-584\"><\/textarea><\/span>\n<\/p>\n<p>\u9700\u8981\u5e2e\u52a9\u7684\u4e8b\u9879\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p>\n\t<font color=\"red\">\n\t<\/font>\n<\/p>\n<H4>\u53d1\u9001\u4e4b\u540e\uff0c\u8bf7\u7f51\u9875\u4e0b\u6ed1\uff0c\u786e\u8ba4\u5df2\u7ecf\u9001\u51fa\u3002\n<\/h4>\n<p><span id=\"wpcf7-6a57aaa1793f2-wrapper\" class=\"wpcf7-form-control-wrap honeypot-472-wrap\" ><label for=\"wpcf7-6a57aaa1793f2-field\" class=\"hp-message\">Please leave this field empty.<\/label><input id=\"wpcf7-6a57aaa1793f2-field\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"honeypot-472\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control has-spinner wpcf7-submit\" type=\"submit\" value=\"\u53d1\u9001\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"220\"\/><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n\/* ]]> *\/\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div><\/section>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":23,"featured_media":0,"parent":3427,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["post-3968","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.8 (Yoast SEO v24.8.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u8054\u7edcBBN\u5173\u4e8e\u5949\u732e<\/title>\n<meta name=\"description\" content=\"Have a question or comment about donating to BBN? This is the place to get the answer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bbn1.bbnradio.org\/schinese\/\u8054\u7edc\u6211\u4eec\/\u8054\u7edc\u6211\u4eec\u5173\u4e8e\u5949\u732e\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u8054\u7edc\u6211\u4eec\u5173\u4e8e\u5949\u732e\" \/>\n<meta property=\"og:description\" content=\"Have a question or comment about donating to BBN? This is the place to get the answer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bbn1.bbnradio.org\/schinese\/\u8054\u7edc\u6211\u4eec\/\u8054\u7edc\u6211\u4eec\u5173\u4e8e\u5949\u732e\/\" \/>\n<meta property=\"og:site_name\" content=\"BBN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BBNChinese\/\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-03T13:18:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u8054\u7edc\u6211\u4eec\u5173\u4e8e\u5949\u732e\" \/>\n<meta name=\"twitter:site\" content=\"@BBNChinese\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bbn1.bbnradio.org\/schinese\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac%e5%85%b3%e4%ba%8e%e5%a5%89%e7%8c%ae\/\",\"url\":\"https:\/\/bbn1.bbnradio.org\/schinese\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac%e5%85%b3%e4%ba%8e%e5%a5%89%e7%8c%ae\/\",\"name\":\"\u8054\u7edcBBN\u5173\u4e8e\u5949\u732e\",\"isPartOf\":{\"@id\":\"https:\/\/bbn1.bbnradio.org\/schinese\/#website\"},\"datePublished\":\"2015-06-18T15:37:20+00:00\",\"dateModified\":\"2018-05-03T13:18:40+00:00\",\"description\":\"Have a question or comment about donating to BBN? This is the place to get the answer.\",\"breadcrumb\":{\"@id\":\"https:\/\/bbn1.bbnradio.org\/schinese\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac%e5%85%b3%e4%ba%8e%e5%a5%89%e7%8c%ae\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bbn1.bbnradio.org\/schinese\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac%e5%85%b3%e4%ba%8e%e5%a5%89%e7%8c%ae\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bbn1.bbnradio.org\/schinese\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac%e5%85%b3%e4%ba%8e%e5%a5%89%e7%8c%ae\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bbn1.bbnradio.org\/schinese\/%e9%a6%96%e9%a1%b5\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u8054\u7edc\u6211\u4eec\",\"item\":\"https:\/\/bbn1.bbnradio.org\/schinese\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u8054\u7edc\u6211\u4eec\u5173\u4e8e\u5949\u732e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bbn1.bbnradio.org\/schinese\/#website\",\"url\":\"https:\/\/bbn1.bbnradio.org\/schinese\/\",\"name\":\"BBN Chinese\",\"description\":\"BBN\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bbn1.bbnradio.org\/schinese\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u8054\u7edcBBN\u5173\u4e8e\u5949\u732e","description":"Have a question or comment about donating to BBN? This is the place to get the answer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bbn1.bbnradio.org\/schinese\/\u8054\u7edc\u6211\u4eec\/\u8054\u7edc\u6211\u4eec\u5173\u4e8e\u5949\u732e\/","og_locale":"zh_CN","og_type":"article","og_title":"\u8054\u7edc\u6211\u4eec\u5173\u4e8e\u5949\u732e","og_description":"Have a question or comment about donating to BBN? This is the place to get the answer.","og_url":"https:\/\/bbn1.bbnradio.org\/schinese\/\u8054\u7edc\u6211\u4eec\/\u8054\u7edc\u6211\u4eec\u5173\u4e8e\u5949\u732e\/","og_site_name":"BBN","article_publisher":"https:\/\/www.facebook.com\/BBNChinese\/","article_modified_time":"2018-05-03T13:18:40+00:00","twitter_card":"summary_large_image","twitter_title":"\u8054\u7edc\u6211\u4eec\u5173\u4e8e\u5949\u732e","twitter_site":"@BBNChinese","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bbn1.bbnradio.org\/schinese\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac%e5%85%b3%e4%ba%8e%e5%a5%89%e7%8c%ae\/","url":"https:\/\/bbn1.bbnradio.org\/schinese\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac%e5%85%b3%e4%ba%8e%e5%a5%89%e7%8c%ae\/","name":"\u8054\u7edcBBN\u5173\u4e8e\u5949\u732e","isPartOf":{"@id":"https:\/\/bbn1.bbnradio.org\/schinese\/#website"},"datePublished":"2015-06-18T15:37:20+00:00","dateModified":"2018-05-03T13:18:40+00:00","description":"Have a question or comment about donating to BBN? This is the place to get the answer.","breadcrumb":{"@id":"https:\/\/bbn1.bbnradio.org\/schinese\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac%e5%85%b3%e4%ba%8e%e5%a5%89%e7%8c%ae\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bbn1.bbnradio.org\/schinese\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac%e5%85%b3%e4%ba%8e%e5%a5%89%e7%8c%ae\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bbn1.bbnradio.org\/schinese\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac%e5%85%b3%e4%ba%8e%e5%a5%89%e7%8c%ae\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bbn1.bbnradio.org\/schinese\/%e9%a6%96%e9%a1%b5\/"},{"@type":"ListItem","position":2,"name":"\u8054\u7edc\u6211\u4eec","item":"https:\/\/bbn1.bbnradio.org\/schinese\/%e8%81%94%e7%bb%9c%e6%88%91%e4%bb%ac\/"},{"@type":"ListItem","position":3,"name":"\u8054\u7edc\u6211\u4eec\u5173\u4e8e\u5949\u732e"}]},{"@type":"WebSite","@id":"https:\/\/bbn1.bbnradio.org\/schinese\/#website","url":"https:\/\/bbn1.bbnradio.org\/schinese\/","name":"BBN Chinese","description":"BBN","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bbn1.bbnradio.org\/schinese\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bbn1.bbnradio.org\/schinese\/wp-json\/wp\/v2\/pages\/3968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bbn1.bbnradio.org\/schinese\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bbn1.bbnradio.org\/schinese\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/schinese\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/schinese\/wp-json\/wp\/v2\/comments?post=3968"}],"version-history":[{"count":2,"href":"https:\/\/bbn1.bbnradio.org\/schinese\/wp-json\/wp\/v2\/pages\/3968\/revisions"}],"predecessor-version":[{"id":15990,"href":"https:\/\/bbn1.bbnradio.org\/schinese\/wp-json\/wp\/v2\/pages\/3968\/revisions\/15990"}],"up":[{"embeddable":true,"href":"https:\/\/bbn1.bbnradio.org\/schinese\/wp-json\/wp\/v2\/pages\/3427"}],"wp:attachment":[{"href":"https:\/\/bbn1.bbnradio.org\/schinese\/wp-json\/wp\/v2\/media?parent=3968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}